{"id":470,"date":"2018-05-22T14:14:54","date_gmt":"2018-05-22T12:14:54","guid":{"rendered":"https:\/\/atswheels.ch\/it\/impressum"},"modified":"2021-03-02T17:25:20","modified_gmt":"2021-03-02T15:25:20","slug":"impressum","status":"publish","type":"page","link":"https:\/\/atswheels.ch\/it\/impressum","title":{"rendered":"Impressum"},"content":{"rendered":"<h1>Impressum<\/h1>\n<p><strong>alurad.ch AG<\/strong><br \/>\nK\u00f6nizstrasse 161 <br \/>\nCH-3097 Liebefeld<\/p>\n<p><a href=\"tel:+41317343939\">Tel: +41 (0) 31 734 39 39<\/a><br \/>\nFax: +41 (0) 31 734 39 30<\/p>\n<p>Web: <a href=\"https:\/\/www.alurad.ch\">www.alurad.ch<\/a> <br \/>\nE-Mail: <a href=\"&#109;&#x61;&#105;&#x6c;&#116;&#x6f;&#58;&#x69;n&#x66;o&#x40;a&#x6c;u&#114;&#x61;&#100;&#x2e;&#99;&#x68;\">i&#110;&#102;&#x6f;&#x40;&#x61;l&#117;&#114;&#x61;&#x64;&#x2e;ch<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Impressum alurad.ch AG K\u00f6nizstrasse 161 CH-3097 Liebefeld Tel: +41 (0) 31 734 39 39 Fax: +41 (0) 31 734 39 30 Web: www.alurad.ch E-Mail: &#x69;&#110;f&#x6f;&#x40;&#97;l&#x75;&#x72;&#97;d&#x2e;&#99;h<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":59,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/atswheels.ch\/it\/wp-json\/wp\/v2\/pages\/470"}],"collection":[{"href":"https:\/\/atswheels.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/atswheels.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/atswheels.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/atswheels.ch\/it\/wp-json\/wp\/v2\/comments?post=470"}],"version-history":[{"count":4,"href":"https:\/\/atswheels.ch\/it\/wp-json\/wp\/v2\/pages\/470\/revisions"}],"predecessor-version":[{"id":762,"href":"https:\/\/atswheels.ch\/it\/wp-json\/wp\/v2\/pages\/470\/revisions\/762"}],"wp:attachment":[{"href":"https:\/\/atswheels.ch\/it\/wp-json\/wp\/v2\/media?parent=470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}